{"id":49,"count":2,"description":"","link":"https:\/\/dulonmarine.com\/hr\/cat\/metal\/","name":"Metal care","slug":"metal","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":7,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Metal care Archieven - Dulon Marine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dulonmarine.com\/hr\/macka\/metal\/\" \/>\n<meta property=\"og:locale\" content=\"hr_HR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Metal care Archieven - Dulon Marine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dulonmarine.com\/hr\/macka\/metal\/\" \/>\n<meta property=\"og:site_name\" content=\"Dulon Marine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/dulonmarine.com\\\/sv\\\/cat\\\/metall\\\/\",\"url\":\"https:\\\/\\\/dulonmarine.com\\\/sv\\\/cat\\\/metall\\\/\",\"name\":\"Metal care Archieven - Dulon Marine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dulonmarine.com\\\/pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dulonmarine.com\\\/sv\\\/cat\\\/metall\\\/#breadcrumb\"},\"inLanguage\":\"hr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dulonmarine.com\\\/sv\\\/cat\\\/metall\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dulonmarine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Metal care\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dulonmarine.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/dulonmarine.com\\\/pt\\\/\",\"name\":\"Dulon Marine\",\"description\":\"Onderhoudsproducten voor de scheepvaart\",\"publisher\":{\"@id\":\"https:\\\/\\\/dulonmarine.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dulonmarine.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dulonmarine.com\\\/pt\\\/#organization\",\"name\":\"Dulon Marine Deckmate Group\",\"url\":\"https:\\\/\\\/dulonmarine.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hr\",\"@id\":\"https:\\\/\\\/dulonmarine.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/dulonmarine.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Dulon-Marine-Deckmate-Group-logo-small.png\",\"contentUrl\":\"http:\\\/\\\/dulonmarine.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Dulon-Marine-Deckmate-Group-logo-small.png\",\"width\":350,\"height\":150,\"caption\":\"Dulon Marine Deckmate Group\"},\"image\":{\"@id\":\"https:\\\/\\\/dulonmarine.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dulonmarine?locale=nl_NL\",\"https:\\\/\\\/www.instagram.com\\\/dulonmarinegroup\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arhiva Metal care - Dulon Marine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dulonmarine.com\/hr\/macka\/metal\/","og_locale":"hr_HR","og_type":"article","og_title":"Metal care Archieven - Dulon Marine","og_url":"https:\/\/dulonmarine.com\/hr\/macka\/metal\/","og_site_name":"Dulon Marine","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/dulonmarine.com\/sv\/cat\/metall\/","url":"https:\/\/dulonmarine.com\/sv\/cat\/metall\/","name":"Arhiva Metal care - Dulon Marine","isPartOf":{"@id":"https:\/\/dulonmarine.com\/pt\/#website"},"breadcrumb":{"@id":"https:\/\/dulonmarine.com\/sv\/cat\/metall\/#breadcrumb"},"inLanguage":"hr"},{"@type":"BreadcrumbList","@id":"https:\/\/dulonmarine.com\/sv\/cat\/metall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dulonmarine.com\/"},{"@type":"ListItem","position":2,"name":"Metal care"}]},{"@type":"WebSite","@id":"https:\/\/dulonmarine.com\/pt\/#website","url":"https:\/\/dulonmarine.com\/pt\/","name":"Dulon Marine","description":"Proizvodi za odr\u017eavanje plovila","publisher":{"@id":"https:\/\/dulonmarine.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dulonmarine.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hr"},{"@type":"Organization","@id":"https:\/\/dulonmarine.com\/pt\/#organization","name":"Dulon Marine Deckmate grupa","url":"https:\/\/dulonmarine.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"hr","@id":"https:\/\/dulonmarine.com\/pt\/#\/schema\/logo\/image\/","url":"http:\/\/dulonmarine.com\/wp-content\/uploads\/2023\/02\/Dulon-Marine-Deckmate-Group-logo-small.png","contentUrl":"http:\/\/dulonmarine.com\/wp-content\/uploads\/2023\/02\/Dulon-Marine-Deckmate-Group-logo-small.png","width":350,"height":150,"caption":"Dulon Marine Deckmate Group"},"image":{"@id":"https:\/\/dulonmarine.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dulonmarine?locale=nl_NL","https:\/\/www.instagram.com\/dulonmarinegroup\/"]}]}},"_links":{"self":[{"href":"https:\/\/dulonmarine.com\/hr\/wp-json\/wp\/v2\/product_cat\/49","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dulonmarine.com\/hr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/dulonmarine.com\/hr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/dulonmarine.com\/hr\/wp-json\/wp\/v2\/product?product_cat=49"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}